{"id":13314,"date":"2024-03-07T14:07:41","date_gmt":"2024-03-07T13:07:41","guid":{"rendered":"https:\/\/gesellschaft-museum.de\/bridge\/?p=13314"},"modified":"2024-03-07T14:07:41","modified_gmt":"2024-03-07T13:07:41","slug":"ein-starkes-team-auf-der-freizeitmesse-in-nuernberg","status":"publish","type":"post","link":"https:\/\/gesellschaft-museum.de\/bridge\/ein-starkes-team-auf-der-freizeitmesse-in-nuernberg\/","title":{"rendered":"Ein starkes Team auf der Freizeitmesse in N\u00fcrnberg"},"content":{"rendered":"<p>Am 24. und 25. M\u00e4rz war unser Club mit einem Stand auf der Freizeitmesse im Messezentrum N\u00fcrnberg vertreten. Dank des Engagements von Susanne Fuchs konnten wir auf 9 m\u00b2 kostenfrei f\u00fcr ein Wochenende den Messebesuchern das Bridgespielen n\u00e4herbringen. Obwohl wir nur in der zweiten Reihe standen, hatte das Standteam alle H\u00e4nde voll zu tun, um die Interessierten an zwei Spieltischen und zur Vorbereitung an einem Stehtisch in die Grundlagen des Spiels einzuweisen. Wir konnten eine ganze Reihe von Kontakten kn\u00fcpfen und bereits erste Anmeldungen f\u00fcr unsere Anf\u00e4ngerkurse feststellen.<\/p>\n<p>Messearbeit ist richtig anstrengend &#8211; ein gro\u00dfes Dankesch\u00f6n an das Standteam und an alle, die mit vor- und nachbereitet haben.<\/p>\n<p>Das Bessere ist der Feind des Guten &#8211; daher werden wir die wertvollen Erkenntnisse aus diesem Messeauftritt auswerten und in die Planung f\u00fcr kommende Auftritte einflie\u00dfen lassen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13316\" src=\"https:\/\/gesellschaft-museum.de\/bridge\/wp-content\/uploads\/sites\/2\/Messe2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/gesellschaft-museum.de\/bridge\/wp-content\/uploads\/sites\/2\/Messe2-300x225.jpg 300w, https:\/\/gesellschaft-museum.de\/bridge\/wp-content\/uploads\/sites\/2\/Messe2-1030x773.jpg 1030w, https:\/\/gesellschaft-museum.de\/bridge\/wp-content\/uploads\/sites\/2\/Messe2-768x576.jpg 768w, https:\/\/gesellschaft-museum.de\/bridge\/wp-content\/uploads\/sites\/2\/Messe2-1536x1152.jpg 1536w, https:\/\/gesellschaft-museum.de\/bridge\/wp-content\/uploads\/sites\/2\/Messe2-1500x1125.jpg 1500w, https:\/\/gesellschaft-museum.de\/bridge\/wp-content\/uploads\/sites\/2\/Messe2-705x529.jpg 705w, https:\/\/gesellschaft-museum.de\/bridge\/wp-content\/uploads\/sites\/2\/Messe2.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 24. und 25. M\u00e4rz war unser Club mit einem Stand auf der Freizeitmesse im Messezentrum N\u00fcrnberg vertreten. Dank des Engagements von Susanne Fuchs konnten wir auf 9 m\u00b2 kostenfrei f\u00fcr ein Wochenende den Messebesuchern das Bridgespielen n\u00e4herbringen. Obwohl wir nur in der zweiten Reihe standen, hatte das Standteam alle H\u00e4nde voll zu tun, um [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":13315,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts\/13314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/comments?post=13314"}],"version-history":[{"count":2,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts\/13314\/revisions"}],"predecessor-version":[{"id":13318,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts\/13314\/revisions\/13318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/media\/13315"}],"wp:attachment":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/media?parent=13314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/categories?post=13314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/tags?post=13314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}