{"id":15980,"date":"2025-06-11T16:57:58","date_gmt":"2025-06-11T14:57:58","guid":{"rendered":"https:\/\/gesellschaft-museum.de\/bridge\/?p=15980"},"modified":"2025-06-11T16:57:58","modified_gmt":"2025-06-11T14:57:58","slug":"individualturnier-und-sommerfest-am-26-juli","status":"publish","type":"post","link":"https:\/\/gesellschaft-museum.de\/bridge\/individualturnier-und-sommerfest-am-26-juli\/","title":{"rendered":"Individualturnier und Sommerfest am 26. Juli"},"content":{"rendered":"<p>Am 26. Juli wollen wir wieder mit einem Individualturnier und anschlie\u00dfendem italienischen Buffet den Sommer feiern! Nach den beiden verregneten Terminen in den Vorjahren steigt die Wahrscheinlichkeit, dass wir nach dem Turnier den Tag bei einem lauen Sommerabend im Garten unserer Villa ausklingen lassen k\u00f6nnen &#8230;<\/p>\n<p>Zum Sommerfest spielen wir ein Individualturnier, bei dem die Partner mit jedem Tisch wechseln, sodass zahlreiche neue und spannende Paarungen entstehen. Daf\u00fcr wird ein ganz einfaches Bietsystem zugrunde gelegt, das vor dem Turnier ausliegt. Eine gute Gelegenheit zum gegenseitigen Kennenlernen!<\/p>\n<p>Wir bitten Sie, bereits um 14 Uhr im Club zu sein, damit die (nicht ganz triviale) Turnierorganisation durch unseren Turnierleiter Ulf Bormann zum Turnierstart um 14:30 Uhr abgeschlossen werden kann.<\/p>\n<p>Anmeldung bitte \u00fcber den Aushang im Club oder auch <a href=\"https:\/\/datenbank.bridge-verband.de\/website\/register\/5229\">hier \u00fcber die DBV-Datenbank.<\/a><\/p>\n<p>Tischgeld incl. aller Speisen und Getr\u00e4nke: Mitglieder 10 \u20ac, G\u00e4ste 20 \u20ac<\/p>\n<p>Kuchenspenden sind erw\u00fcnscht und werden mit einem Tischgeld-Abzug von 5 \u20ac belohnt. Gerne auf der aush\u00e4ngenden Kuchenliste eintragen.<\/p>\n<p>Wir freuen uns auf zahlreiche Anmeldungen und auf ein sch\u00f6nes, sommerliches Fest.<\/p>\n<p>Ihr Vorstand<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 26. Juli wollen wir wieder mit einem Individualturnier und anschlie\u00dfendem italienischen Buffet den Sommer feiern! Nach den beiden verregneten Terminen in den Vorjahren steigt die Wahrscheinlichkeit, dass wir nach dem Turnier den Tag bei einem lauen Sommerabend im Garten unserer Villa ausklingen lassen k\u00f6nnen &#8230; Zum Sommerfest spielen wir ein Individualturnier, bei dem die [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":15983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts\/15980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/comments?post=15980"}],"version-history":[{"count":4,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts\/15980\/revisions"}],"predecessor-version":[{"id":17656,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts\/15980\/revisions\/17656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/media\/15983"}],"wp:attachment":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/media?parent=15980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/categories?post=15980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/tags?post=15980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}