{"id":9574,"date":"2022-03-13T15:13:44","date_gmt":"2022-03-13T14:13:44","guid":{"rendered":"https:\/\/gesellschaft-museum.de\/bridge\/?p=9574"},"modified":"2022-03-13T15:13:51","modified_gmt":"2022-03-13T14:13:51","slug":"termine-spieltechnik-workshop","status":"publish","type":"post","link":"https:\/\/gesellschaft-museum.de\/bridge\/termine-spieltechnik-workshop\/","title":{"rendered":"Termine Spieltechnik Workshop"},"content":{"rendered":"<p>Die weiteren Termine f\u00fcr den Spieltechnik Workshop sind<\/p>\n<ul>\n<li>Sonntag, 10. April 2022<\/li>\n<li>Samstag, 7.Mai 2022<\/li>\n<li>Samstag, 11. Juni 2022<\/li>\n<li>Sonntag, 10 Juli 2022<\/li>\n<\/ul>\n<p>Beginn ist jeweils 10 Uhr. Ein Joker steht zur Verf\u00fcgung.<\/p>\n<p>Es werden jeweils 8 Boards auf BBO gespielt. Anschlie\u00dfend findet eine Besprechung der Boards unter Zoom statt.<\/p>\n<p>Die Kosten betragen 5 \u20ac pro Person und Termin, die f\u00fcr einen guten Zweck (z.B. unicef) gespendet werden. Die Abrechnung erfolgt einmal pro Halbjahr.<\/p>\n<p>Kursleiter: Ulf Bormann<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die weiteren Termine f\u00fcr den Spieltechnik Workshop sind Sonntag, 10. April 2022 Samstag, 7.Mai 2022 Samstag, 11. Juni 2022 Sonntag, 10 Juli 2022 Beginn ist jeweils 10 Uhr. Ein Joker steht zur Verf\u00fcgung. Es werden jeweils 8 Boards auf BBO gespielt. Anschlie\u00dfend findet eine Besprechung der Boards unter Zoom statt. Die Kosten betragen 5 \u20ac [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":5051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,106,105],"tags":[],"class_list":["post-9574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-ankuendigungen","category-unterricht"],"_links":{"self":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts\/9574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/comments?post=9574"}],"version-history":[{"count":1,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts\/9574\/revisions"}],"predecessor-version":[{"id":9575,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts\/9574\/revisions\/9575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/media\/5051"}],"wp:attachment":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/media?parent=9574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/categories?post=9574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/tags?post=9574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}