{"id":108,"count":1,"description":"","link":"https:\/\/gesellschaft-museum.de\/bridge\/schlagwort\/clubmeisterschaft\/","name":"Clubmeisterschaft","slug":"clubmeisterschaft","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/tags\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts?tags=108"},{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/portfolio?tags=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}