{"id":122,"count":1,"description":"","link":"https:\/\/gesellschaft-museum.de\/bridge\/schlagwort\/hilfe\/","name":"Hilfe","slug":"hilfe","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/tags\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts?tags=122"},{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/portfolio?tags=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}