{"id":208,"count":1,"description":"","link":"https:\/\/gesellschaft-museum.de\/bridge\/schlagwort\/traudl\/","name":"Traudl","slug":"traudl","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/tags\/208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/posts?tags=208"},{"href":"https:\/\/gesellschaft-museum.de\/bridge\/wp-json\/wp\/v2\/portfolio?tags=208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}